{"id":303,"date":"2018-07-23T16:32:12","date_gmt":"2018-07-23T16:32:12","guid":{"rendered":"https:\/\/corposalud.merida.gob.ve\/?page_id=303"},"modified":"2022-05-11T17:13:54","modified_gmt":"2022-05-11T17:13:54","slug":"coordinacion-control-de-gestion","status":"publish","type":"page","link":"https:\/\/corposalud.merida.gob.ve\/index.php\/coordinacion-control-de-gestion\/","title":{"rendered":"Coordinaci\u00f3n Control De Gesti\u00f3n"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"303\" class=\"elementor elementor-303\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-a9e31d8 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a9e31d8\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7bed2b6\" data-id=\"7bed2b6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15789ba elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"15789ba\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-medium\">COORDINACI\u00d3N CONTROL DE GESTI\u00d3N<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ec70a8 elementor-widget elementor-widget-spacer\" data-id=\"3ec70a8\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-inner-section elementor-element elementor-element-cc865e8 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc865e8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ff3d39d\" data-id=\"ff3d39d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b74cb75 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"b74cb75\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1 style=\"text-align: center;\">Objetivo<\/h1><p>Fortalecer los mecanismos de control interno existentes, promoviendo el correcto uso de los recursos, a trav\u00e9s de la implementaci\u00f3n de herramientas administrativas que permitan el seguimiento y control de las actividades realizadas por la gesti\u00f3n, en armon\u00eda con las disposiciones legales vigentes y respetando los principios de: legalidad, exactitud y transparencia, eficacia, econom\u00eda, eficiencia e impacto social.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9a83e13\" data-id=\"9a83e13\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61f7de8 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"61f7de8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"235\" height=\"231\" src=\"https:\/\/corposalud.merida.gob.ve\/wp-content\/uploads\/2018\/08\/objetivos.png\" class=\"attachment-large size-large wp-image-757\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ef9354 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"9ef9354\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1 style=\"text-align: center;\">Funciones Espec\u00edficas<\/h1><p>\u2666 Ser enlace institucional entre la Corporaci\u00f3n de Salud del estado M\u00e9rida y la Unidad de Control de Gesti\u00f3n de la Gobernaci\u00f3n del estado M\u00e9rida.<\/p><p>\u2666 Realizar el seguimiento, evaluaci\u00f3n y control del cumplimiento de las metas, objetivos, planes y actividades realizadas por las unidades y dependencias adscritas a la Corporaci\u00f3n de Salud del estado M\u00e9rida.<\/p><p>\u2666 Exhibir claramente la situaci\u00f3n real de la instituci\u00f3n, con informaci\u00f3n simple, completa y actualizada sobre la situaci\u00f3n interna y externa.<\/p><p>\u2666 Detectar y facilitar el aprovechamiento de las oportunidades y fortalezas, as\u00ed como reducir amenazas y debilidades que se detecten.<\/p><p>\u2666 Evaluar la informaci\u00f3n que suministren las distintas unidades y dependencias sobre la ejecuci\u00f3n de los planes desarrollados en el sector salud.<\/p><p>\u2666 Recabar la informaci\u00f3n necesaria para la producci\u00f3n de los indicadores de gesti\u00f3n en el sector salud.<\/p><p>\u2666 Inspeccionar y evaluar la gesti\u00f3n de las distintas unidades y dependencias adscritas a la Corporaci\u00f3n de Salud del estado M\u00e9rida.<\/p><p>\u2666 Verificar la elaboraci\u00f3n e implementaci\u00f3n de: normas, procedimientos, herramientas de control interno y medici\u00f3n de resultados que permitan verificar la ejecuci\u00f3n \u00f3ptima de pol\u00edticas, planes, programas, proyectos y acciones, determinando el cumplimiento efectivo de objetivos y metas, as\u00ed como generar informaci\u00f3n t\u00e9cnica, objetiva y confiable que sirva de insumo para la planificaci\u00f3n, programaci\u00f3n y toma de decisiones.<\/p><p>\u2666 Velar por el correcto cumplimiento de los mecanismos de Control Internos implementados.<\/p><p>\u2666 Supervisar, evaluar y asesorar a las unidades y dependencias adscritas a la Corporaci\u00f3n de Salud del estado M\u00e9rida, con respecto a la organizaci\u00f3n administrativa, al mejoramiento y cumplimento efectivo de los procedimientos establecidos en las normas legales vigentes, de manera de garantizar mayor eficacia en el desarrollo de las actividades.<\/p><p>\u2666 Recopilar informaci\u00f3n de las unidades y dependencias adscritas a la Corporaci\u00f3n de Salud del estado M\u00e9rida, a trav\u00e9s de formatos que permitan la eficiente recolecci\u00f3n de los datos.<\/p><p>\u2666 Recopilar, clasificar y analizar la informaci\u00f3n para la elaboraci\u00f3n y presentaci\u00f3n trimestralmente del Informe de Gesti\u00f3n a la Unidad de Control de Gesti\u00f3n de la Gobernaci\u00f3n del estado M\u00e9rida.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>COORDINACI\u00d3N CONTROL DE GESTI\u00d3N Objetivo Fortalecer los mecanismos de control interno existentes, promoviendo el correcto uso de los recursos, a trav\u00e9s de la implementaci\u00f3n de herramientas administrativas que permitan el seguimiento y control de las actividades realizadas por la gesti\u00f3n, en armon\u00eda con las disposiciones legales vigentes y respetando los principios de: legalidad, exactitud y [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_monsterinsights_skip_tracking":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-303","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/corposalud.merida.gob.ve\/index.php\/wp-json\/wp\/v2\/pages\/303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corposalud.merida.gob.ve\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/corposalud.merida.gob.ve\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/corposalud.merida.gob.ve\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/corposalud.merida.gob.ve\/index.php\/wp-json\/wp\/v2\/comments?post=303"}],"version-history":[{"count":0,"href":"https:\/\/corposalud.merida.gob.ve\/index.php\/wp-json\/wp\/v2\/pages\/303\/revisions"}],"wp:attachment":[{"href":"https:\/\/corposalud.merida.gob.ve\/index.php\/wp-json\/wp\/v2\/media?parent=303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}